{"id":5558,"date":"2025-07-10T19:46:04","date_gmt":"2025-07-10T19:46:04","guid":{"rendered":"https:\/\/jjgomezcorp.com\/maquinaria\/"},"modified":"2025-10-21T18:50:19","modified_gmt":"2025-10-21T18:50:19","slug":"maquinaria","status":"publish","type":"page","link":"https:\/\/jjgomezcorp.com\/es\/maquinaria\/","title":{"rendered":"Maquinaria"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00bb1&#8243; admin_label=\u00bbHero Section\u00bb _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb0|0px|0px|0px\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row column_structure=\u00bb1_2,1_2&#8243; make_equal=\u00bbon\u00bb _builder_version=\u00bb4.27.4&#8243; width=\u00bb100%\u00bb max_width=\u00bb100%\u00bb custom_padding=\u00bb0px|0|0px|\u00bb use_custom_width=\u00bbon\u00bb width_unit=\u00bboff\u00bb custom_width_percent=\u00bb100%\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb200px|8%|260px|8%\u00bb custom_padding_tablet=\u00bb80px|10%|80px|10%\u00bb custom_padding_phone=\u00bb80px|10%|80px|10%\u00bb custom_padding_last_edited=\u00bbon|tablet\u00bb global_colors_info=\u00bb{}\u00bb padding_tablet=\u00bb80px|10%|80px|10%\u00bb padding_last_edited=\u00bbon|tablet\u00bb custom_padding__hover=\u00bb|||\u00bb padding_phone=\u00bb80px|10%|80px|10%\u00bb][et_pb_text _builder_version=\u00bb4.27.4&#8243; text_font=\u00bb||||||||\u00bb header_font=\u00bb||||||||\u00bb header_3_font=\u00bbKarla|700||on|||||\u00bb header_3_text_color=\u00bb#c2ab92&#8243; header_3_font_size=\u00bb16px\u00bb header_3_letter_spacing=\u00bb1px\u00bb background_layout=\u00bbdark\u00bb max_width=\u00bb600px\u00bb module_alignment=\u00bbleft\u00bb custom_margin=\u00bb||20px|\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h3>Dise\u00f1ado para sus necesidades<\/h3>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.27.4&#8243; text_font=\u00bbKarla||||||||\u00bb text_font_size=\u00bb18px\u00bb text_line_height=\u00bb1.8em\u00bb header_font=\u00bb&#8211;et_global_heading_font||||||||\u00bb header_font_size=\u00bb56px\u00bb header_line_height=\u00bb1.4em\u00bb header_2_font=\u00bb||||||||\u00bb header_3_font=\u00bb||||||||\u00bb max_width=\u00bb600px\u00bb header_font_size_tablet=\u00bb40px\u00bb header_font_size_phone=\u00bb\u00bb header_font_size_last_edited=\u00bbon|tablet\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h1>Maquinaria<\/h1>\n<p>JJG se especializa en ofrecer soluciones industriales innovadoras y personalizadas. En colaboraci\u00f3n con nuestros socios de la industria, coordinamos el dise\u00f1o, la fabricaci\u00f3n y la instalaci\u00f3n de equipos e infraestructura de alto rendimiento adaptados a las necesidades \u00fanicas de cada cliente.[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.27.4&#8243; background_color=\u00bb#121212&#8243; use_background_color_gradient=\u00bbon\u00bb background_color_gradient_stops=\u00bbrgba(18,18,18,0.5) 0%|#121212 100%\u00bb background_color_gradient_overlays_image=\u00bbon\u00bb background_color_gradient_start=\u00bbrgba(18,18,18,0.5)\u00bb background_color_gradient_end=\u00bb#121212&#8243; background_image=\u00bbhttps:\/\/jjgomezcorp.com\/wp-content\/uploads\/2025\/07\/machinery-01.png\u00bb custom_padding=\u00bb200px||260px|8%\u00bb custom_padding_tablet=\u00bb80px|10%|80px|10%\u00bb custom_padding_phone=\u00bb80px|10%|80px|10%\u00bb custom_padding_last_edited=\u00bbon|desktop\u00bb global_colors_info=\u00bb{}\u00bb padding_tablet=\u00bb80px|10%|80px|10%\u00bb padding_last_edited=\u00bbon|desktop\u00bb custom_padding__hover=\u00bb|||\u00bb padding_phone=\u00bb80px|10%|80px|10%\u00bb][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.16&#8243; background_color=\u00bb#121212&#8243; custom_padding=\u00bb0|0px|100px|0px\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row column_structure=\u00bb1_2,1_2&#8243; _builder_version=\u00bb4.16&#8243; custom_margin=\u00bb|||\u00bb animation_direction=\u00bbbottom\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_image src=\u00bbhttps:\/\/jjgomezcorp.com\/wp-content\/uploads\/2025\/07\/machinery-02.png\u00bb title_text=\u00bbmachinery-02&#8243; align=\u00bbcenter\u00bb align_tablet=\u00bbcenter\u00bb align_phone=\u00bbcenter\u00bb align_last_edited=\u00bbon|desktop\u00bb _builder_version=\u00bb4.27.4&#8243; custom_margin=\u00bb-160px|||\u00bb custom_margin_tablet=\u00bb0px|||\u00bb custom_margin_phone=\u00bb\u00bb custom_margin_last_edited=\u00bbon|tablet\u00bb animation_style=\u00bbslide\u00bb animation_direction=\u00bbbottom\u00bb animation_intensity_slide=\u00bb6%\u00bb animation_starting_opacity=\u00bb50%\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttps:\/\/jjgomezcorp.com\/wp-content\/uploads\/2025\/07\/machinery-03.png\u00bb title_text=\u00bbmachinery-03&#8243; align=\u00bbcenter\u00bb align_tablet=\u00bbcenter\u00bb align_phone=\u00bbcenter\u00bb align_last_edited=\u00bbon|desktop\u00bb _builder_version=\u00bb4.27.4&#8243; custom_margin=\u00bb-160px|||\u00bb custom_margin_tablet=\u00bb0px|||\u00bb custom_margin_phone=\u00bb\u00bb custom_margin_last_edited=\u00bbon|tablet\u00bb animation_style=\u00bbslide\u00bb animation_direction=\u00bbbottom\u00bb animation_intensity_slide=\u00bb6%\u00bb animation_starting_opacity=\u00bb50%\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.16&#8243; background_color=\u00bb#1b1b1b\u00bb custom_margin=\u00bb50px||50px|\u00bb custom_padding=\u00bb50px|40px|50px|40px\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_text _builder_version=\u00bb4.27.4&#8243; text_font=\u00bbKarla||||||||\u00bb text_text_color=\u00bbrgba(255,255,255,0.7)\u00bb text_font_size=\u00bb18px\u00bb text_line_height=\u00bb1.8em\u00bb header_font=\u00bb||||||||\u00bb header_2_font=\u00bb&#8211;et_global_heading_font||||||||\u00bb header_2_font_size=\u00bb32px\u00bb header_2_line_height=\u00bb1.4em\u00bb header_3_font=\u00bb||||||||\u00bb text_orientation=\u00bbcenter\u00bb background_layout=\u00bbdark\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h2> Ya sea que est\u00e9 construyendo una nueva instalaci\u00f3n o modernizando las operaciones existentes, JJG es su socio en innovaci\u00f3n industrial, ofreciendo soluciones eficientes, seguras y rentables.<\/h2>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_3,1_3,1_3&#8243; _builder_version=\u00bb4.16&#8243; custom_margin=\u00bb||60px|\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_blurb title=\u00bbDise\u00f1o e instalaci\u00f3n de plantas industriales\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#x5a;||divi||400&#8243; icon_placement=\u00bbleft\u00bb _builder_version=\u00bb4.27.4&#8243; header_font=\u00bb&#8211;et_global_heading_font||||||||\u00bb header_font_size=\u00bb24px\u00bb header_line_height=\u00bb1.8em\u00bb body_font=\u00bbKarla||||||||\u00bb body_text_color=\u00bbrgba(255,255,255,0.7)\u00bb body_font_size=\u00bb18px\u00bb body_line_height=\u00bb1.8em\u00bb text_orientation=\u00bbcenter\u00bb background_layout=\u00bbdark\u00bb animation=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb]Soluciones completas para sistemas de tuber\u00edas (aire, agua, vapor, gas, productos qu\u00edmicos).[\/et_pb_blurb][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_blurb title=\u00bbFabricaci\u00f3n de equipos a medida\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#x5a;||divi||400&#8243; icon_placement=\u00bbleft\u00bb _builder_version=\u00bb4.27.4&#8243; header_font=\u00bb&#8211;et_global_heading_font||||||||\u00bb header_font_size=\u00bb24px\u00bb header_line_height=\u00bb1.8em\u00bb body_font=\u00bbKarla||||||||\u00bb body_text_color=\u00bbrgba(255,255,255,0.7)\u00bb body_font_size=\u00bb18px\u00bb body_line_height=\u00bb1.8em\u00bb text_orientation=\u00bbcenter\u00bb background_layout=\u00bbdark\u00bb animation=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb]Tanques de acero inoxidable y acero al carbono, autoclaves, condensadores, calentadores serpent\u00edn y m\u00e1s, todo elaborado con precisi\u00f3n y durabilidad.[\/et_pb_blurb][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_blurb title=\u00bbSoldadura especializada y corte por l\u00e1ser\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#x5a;||divi||400&#8243; icon_placement=\u00bbleft\u00bb _builder_version=\u00bb4.27.4&#8243; header_font=\u00bb&#8211;et_global_heading_font||||||||\u00bb header_font_size=\u00bb24px\u00bb header_line_height=\u00bb1.8em\u00bb body_font=\u00bbKarla||||||||\u00bb body_text_color=\u00bbrgba(255,255,255,0.7)\u00bb body_font_size=\u00bb18px\u00bb body_line_height=\u00bb1.8em\u00bb text_orientation=\u00bbcenter\u00bb background_layout=\u00bbdark\u00bb animation=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb]Acabados de alta calidad e integridad estructural utilizando t\u00e9cnicas y materiales avanzados.[\/et_pb_blurb][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_2,1_2&#8243; _builder_version=\u00bb4.16&#8243; custom_margin=\u00bb||60px|\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_blurb title=\u00bbMaquinaria a medida para la industria alimentaria\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#x5a;||divi||400&#8243; icon_placement=\u00bbleft\u00bb _builder_version=\u00bb4.27.4&#8243; header_font=\u00bb&#8211;et_global_heading_font||||||||\u00bb header_font_size=\u00bb24px\u00bb header_line_height=\u00bb1.8em\u00bb body_font=\u00bbKarla||||||||\u00bb body_text_color=\u00bbrgba(255,255,255,0.7)\u00bb body_font_size=\u00bb18px\u00bb body_line_height=\u00bb1.8em\u00bb text_orientation=\u00bbcenter\u00bb background_layout=\u00bbdark\u00bb animation=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb]Desde cortadoras automatizadas hasta tanques de almacenamiento aislados y tinas de cocci\u00f3n, simplificamos y optimizamos su proceso de producci\u00f3n.[\/et_pb_blurb][\/et_pb_column][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_blurb title=\u00bbFormado y mantenimiento de chapa met\u00e1lica\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#x5a;||divi||400&#8243; icon_placement=\u00bbleft\u00bb _builder_version=\u00bb4.27.4&#8243; header_font=\u00bb&#8211;et_global_heading_font||||||||\u00bb header_font_size=\u00bb24px\u00bb header_line_height=\u00bb1.8em\u00bb body_font=\u00bbKarla||||||||\u00bb body_text_color=\u00bbrgba(255,255,255,0.7)\u00bb body_font_size=\u00bb18px\u00bb body_line_height=\u00bb1.8em\u00bb text_orientation=\u00bbcenter\u00bb background_layout=\u00bbdark\u00bb animation=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb]Incluyendo escaleras, barandillas y equipos de proceso complejos, con servicios completos de transporte y manipulaci\u00f3n.[\/et_pb_blurb][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; admin_label=\u00bbContact\u00bb _builder_version=\u00bb4.16&#8243; background_color=\u00bb#1b1b1b\u00bb custom_padding=\u00bb100px|0px|100px|0px\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row column_structure=\u00bb1_2,1_2&#8243; _builder_version=\u00bb4.16&#8243; global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_text _builder_version=\u00bb4.27.4&#8243; text_font=\u00bbKarla||||||||\u00bb text_text_color=\u00bbrgba(255,255,255,0.7)\u00bb text_font_size=\u00bb18px\u00bb text_line_height=\u00bb1.8em\u00bb header_font=\u00bb||||||||\u00bb header_2_font=\u00bb&#8211;et_global_heading_font||||||||\u00bb header_2_font_size=\u00bb40px\u00bb header_2_line_height=\u00bb1.4em\u00bb header_3_font=\u00bb||||||||\u00bb background_layout=\u00bbdark\u00bb max_width=\u00bb600px\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h2>Hag\u00e1moslo realidad<\/h2>\n<p>\u00bfListo para dar el siguiente paso? Cont\u00e1ctenos hoy y construyamos algo grandioso.<\/p>\n<p><strong>sales@jjgomezcorp.com<\/strong><br \/>\n<strong>Alhambra, CA. 91802-9998  <\/strong><br \/>\n<strong>323-844-3864<\/strong>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_contact_form captcha=\u00bboff\u00bb email=\u00bbjoseggomez423@gmail.com, rod.perales@gmail.com\u00bb module_id=\u00bbet_pb_contact_form_0&#8243; _builder_version=\u00bb4.27.4&#8243; form_field_background_color=\u00bb#242424&#8243; form_field_text_color=\u00bbrgba(255,255,255,0.5)\u00bb form_field_font=\u00bbKarla||||||||\u00bb form_field_font_size=\u00bb16px\u00bb custom_button=\u00bbon\u00bb button_text_size=\u00bb15px\u00bb button_text_color=\u00bb#c2ab92&#8243; button_border_width=\u00bb0px\u00bb button_letter_spacing=\u00bb1px\u00bb button_font=\u00bbKarla|700||on|||||\u00bb button_icon=\u00bb&#x4b;||divi||400&#8243; button_icon_placement=\u00bbleft\u00bb button_on_hover=\u00bboff\u00bb custom_padding=\u00bb|||\u00bb form_background_color=\u00bb#242424&#8243; global_colors_info=\u00bb{}\u00bb][et_pb_contact_field field_id=\u00bbName\u00bb field_title=\u00bbNombre\u00bb _builder_version=\u00bb4.16&#8243; global_colors_info=\u00bb{}\u00bb button_text_size__hover_enabled=\u00bboff\u00bb button_one_text_size__hover_enabled=\u00bboff\u00bb button_two_text_size__hover_enabled=\u00bboff\u00bb button_text_color__hover_enabled=\u00bboff\u00bb button_one_text_color__hover_enabled=\u00bboff\u00bb button_two_text_color__hover_enabled=\u00bboff\u00bb button_border_width__hover_enabled=\u00bboff\u00bb button_one_border_width__hover_enabled=\u00bboff\u00bb button_two_border_width__hover_enabled=\u00bboff\u00bb button_border_color__hover_enabled=\u00bboff\u00bb button_one_border_color__hover_enabled=\u00bboff\u00bb button_two_border_color__hover_enabled=\u00bboff\u00bb button_border_radius__hover_enabled=\u00bboff\u00bb button_one_border_radius__hover_enabled=\u00bboff\u00bb button_two_border_radius__hover_enabled=\u00bboff\u00bb button_letter_spacing__hover_enabled=\u00bboff\u00bb button_one_letter_spacing__hover_enabled=\u00bboff\u00bb button_two_letter_spacing__hover_enabled=\u00bboff\u00bb button_bg_color__hover_enabled=\u00bboff\u00bb button_one_bg_color__hover_enabled=\u00bboff\u00bb button_two_bg_color__hover_enabled=\u00bboff\u00bb][\/et_pb_contact_field][et_pb_contact_field field_id=\u00bbLast_Name\u00bb field_title=\u00bbApellido\u00bb _builder_version=\u00bb4.27.4&#8243; global_colors_info=\u00bb{}\u00bb button_text_size__hover_enabled=\u00bboff\u00bb button_one_text_size__hover_enabled=\u00bboff\u00bb button_two_text_size__hover_enabled=\u00bboff\u00bb button_text_color__hover_enabled=\u00bboff\u00bb button_one_text_color__hover_enabled=\u00bboff\u00bb button_two_text_color__hover_enabled=\u00bboff\u00bb button_border_width__hover_enabled=\u00bboff\u00bb button_one_border_width__hover_enabled=\u00bboff\u00bb button_two_border_width__hover_enabled=\u00bboff\u00bb button_border_color__hover_enabled=\u00bboff\u00bb button_one_border_color__hover_enabled=\u00bboff\u00bb button_two_border_color__hover_enabled=\u00bboff\u00bb button_border_radius__hover_enabled=\u00bboff\u00bb button_one_border_radius__hover_enabled=\u00bboff\u00bb button_two_border_radius__hover_enabled=\u00bboff\u00bb button_letter_spacing__hover_enabled=\u00bboff\u00bb button_one_letter_spacing__hover_enabled=\u00bboff\u00bb button_two_letter_spacing__hover_enabled=\u00bboff\u00bb button_bg_color__hover_enabled=\u00bboff\u00bb button_one_bg_color__hover_enabled=\u00bboff\u00bb button_two_bg_color__hover_enabled=\u00bboff\u00bb][\/et_pb_contact_field][et_pb_contact_field field_id=\u00bbCompany_Name\u00bb field_title=\u00bbNombre de la empresa\u00bb _builder_version=\u00bb4.27.4&#8243; global_colors_info=\u00bb{}\u00bb button_text_size__hover_enabled=\u00bboff\u00bb button_one_text_size__hover_enabled=\u00bboff\u00bb button_two_text_size__hover_enabled=\u00bboff\u00bb button_text_color__hover_enabled=\u00bboff\u00bb button_one_text_color__hover_enabled=\u00bboff\u00bb button_two_text_color__hover_enabled=\u00bboff\u00bb button_border_width__hover_enabled=\u00bboff\u00bb button_one_border_width__hover_enabled=\u00bboff\u00bb button_two_border_width__hover_enabled=\u00bboff\u00bb button_border_color__hover_enabled=\u00bboff\u00bb button_one_border_color__hover_enabled=\u00bboff\u00bb button_two_border_color__hover_enabled=\u00bboff\u00bb button_border_radius__hover_enabled=\u00bboff\u00bb button_one_border_radius__hover_enabled=\u00bboff\u00bb button_two_border_radius__hover_enabled=\u00bboff\u00bb button_letter_spacing__hover_enabled=\u00bboff\u00bb button_one_letter_spacing__hover_enabled=\u00bboff\u00bb button_two_letter_spacing__hover_enabled=\u00bboff\u00bb button_bg_color__hover_enabled=\u00bboff\u00bb button_one_bg_color__hover_enabled=\u00bboff\u00bb button_two_bg_color__hover_enabled=\u00bboff\u00bb][\/et_pb_contact_field][et_pb_contact_field field_id=\u00bbEmail\u00bb field_title=\u00bbDirecci\u00f3n de correo electr\u00f3nico\u00bb field_type=\u00bbemail\u00bb _builder_version=\u00bb4.16&#8243; global_colors_info=\u00bb{}\u00bb button_text_size__hover_enabled=\u00bboff\u00bb button_one_text_size__hover_enabled=\u00bboff\u00bb button_two_text_size__hover_enabled=\u00bboff\u00bb button_text_color__hover_enabled=\u00bboff\u00bb button_one_text_color__hover_enabled=\u00bboff\u00bb button_two_text_color__hover_enabled=\u00bboff\u00bb button_border_width__hover_enabled=\u00bboff\u00bb button_one_border_width__hover_enabled=\u00bboff\u00bb button_two_border_width__hover_enabled=\u00bboff\u00bb button_border_color__hover_enabled=\u00bboff\u00bb button_one_border_color__hover_enabled=\u00bboff\u00bb button_two_border_color__hover_enabled=\u00bboff\u00bb button_border_radius__hover_enabled=\u00bboff\u00bb button_one_border_radius__hover_enabled=\u00bboff\u00bb button_two_border_radius__hover_enabled=\u00bboff\u00bb button_letter_spacing__hover_enabled=\u00bboff\u00bb button_one_letter_spacing__hover_enabled=\u00bboff\u00bb button_two_letter_spacing__hover_enabled=\u00bboff\u00bb button_bg_color__hover_enabled=\u00bboff\u00bb button_one_bg_color__hover_enabled=\u00bboff\u00bb button_two_bg_color__hover_enabled=\u00bboff\u00bb][\/et_pb_contact_field][et_pb_contact_field field_id=\u00bbTitle\u00bb field_title=\u00bbT\u00edtulo\u00bb field_type=\u00bbselect\u00bb select_options=\u00bb%91{%22value%22:%22Alta gerencia%22,%22checked%22:0,%22dragID%22:-1},{%22value%22:%22Adquisiciones%92\/compras%22,%22checked%22:0,%22dragID%22:0},{%22value%22:%22Director de ingenier\u00eda%22,%22checked%22:0,%22dragID%22:1},{%22value%22:%22Gerente de proyecto%22,%22checked%22:0,%22dragID%22:2},{%22value%22:%22Ingeniero de proyecto%22,%22checked%22:0,%22dragID%22:3},{%22value%22:%22Gerencia de planta%22,%22checked%22:0,%22dragID%22:4},{%22value%22:%22Ingenier\u00eda de planta%22,%22checked%22:0,%22dragID%22:5},{%22value%22:%22Gerente de construcci\u00f3n%22,%22checked%22:0,%22dragID%22:6},{%22value%22:%22Otro%22,%22checked%22:0,%22dragID%22:7}%93&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_contact_field][et_pb_contact_field field_id=\u00bbIndustry\u00bb field_title=\u00bbIndustria\u00bb field_type=\u00bbselect\u00bb select_options=\u00bb%91{%22value%22:%22Snack food%22,%22checked%22:0,%22dragID%22:-1},{%22value%22:%22Panader\u00eda%22,%22checked%22:0,%22dragID%22:0},{%22value%22:%22Tortilla%22,%22checked%22:0,%22dragID%22:1},{%22value%22:%22Salsa%22,%22checked%22:0,%22dragID%22:2},{%22value%22:%22Vegetales%22,%22checked%22:0,%22dragID%22:3},{%22value%22:%22Condimentos%22,%22checked%22:0,%22dragID%22:4},{%22value%22:%22Bebidas%22,%22checked%22:0,%22dragID%22:5},{%22value%22:%22Otro%22,%22checked%22:0,%22dragID%22:6}%93&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_contact_field][et_pb_contact_field field_id=\u00bbMessage\u00bb field_title=\u00bbMensaje\u00bb field_type=\u00bbtext\u00bb fullwidth_field=\u00bbon\u00bb _builder_version=\u00bb4.16&#8243; global_colors_info=\u00bb{}\u00bb button_text_size__hover_enabled=\u00bboff\u00bb button_one_text_size__hover_enabled=\u00bboff\u00bb button_two_text_size__hover_enabled=\u00bboff\u00bb button_text_color__hover_enabled=\u00bboff\u00bb button_one_text_color__hover_enabled=\u00bboff\u00bb button_two_text_color__hover_enabled=\u00bboff\u00bb button_border_width__hover_enabled=\u00bboff\u00bb button_one_border_width__hover_enabled=\u00bboff\u00bb button_two_border_width__hover_enabled=\u00bboff\u00bb button_border_color__hover_enabled=\u00bboff\u00bb button_one_border_color__hover_enabled=\u00bboff\u00bb button_two_border_color__hover_enabled=\u00bboff\u00bb button_border_radius__hover_enabled=\u00bboff\u00bb button_one_border_radius__hover_enabled=\u00bboff\u00bb button_two_border_radius__hover_enabled=\u00bboff\u00bb button_letter_spacing__hover_enabled=\u00bboff\u00bb button_one_letter_spacing__hover_enabled=\u00bboff\u00bb button_two_letter_spacing__hover_enabled=\u00bboff\u00bb button_bg_color__hover_enabled=\u00bboff\u00bb button_one_bg_color__hover_enabled=\u00bboff\u00bb button_two_bg_color__hover_enabled=\u00bboff\u00bb][\/et_pb_contact_field][\/et_pb_contact_form][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dise\u00f1ado para sus necesidadesMaquinaria JJG se especializa en ofrecer soluciones industriales innovadoras y personalizadas. En colaboraci\u00f3n con nuestros socios de la industria, coordinamos el dise\u00f1o, la fabricaci\u00f3n y la instalaci\u00f3n de equipos e infraestructura de alto rendimiento adaptados a las necesidades \u00fanicas de cada cliente. Ya sea que est\u00e9 construyendo una nueva instalaci\u00f3n o modernizando [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-5558","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/jjgomezcorp.com\/es\/wp-json\/wp\/v2\/pages\/5558","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jjgomezcorp.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/jjgomezcorp.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/jjgomezcorp.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/jjgomezcorp.com\/es\/wp-json\/wp\/v2\/comments?post=5558"}],"version-history":[{"count":10,"href":"https:\/\/jjgomezcorp.com\/es\/wp-json\/wp\/v2\/pages\/5558\/revisions"}],"predecessor-version":[{"id":6079,"href":"https:\/\/jjgomezcorp.com\/es\/wp-json\/wp\/v2\/pages\/5558\/revisions\/6079"}],"wp:attachment":[{"href":"https:\/\/jjgomezcorp.com\/es\/wp-json\/wp\/v2\/media?parent=5558"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}